{"id":950,"date":"2003-04-13T00:00:00","date_gmt":"2003-04-13T00:00:00","guid":{"rendered":"http:\/\/dominik.stierli.net\/blog\/?p=950"},"modified":"2014-05-20T21:41:50","modified_gmt":"2014-05-20T21:41:50","slug":"wieder-am-arbeiten-australien-party","status":"publish","type":"post","link":"https:\/\/www.stierli.net\/dominik\/wieder-am-arbeiten-australien-party\/","title":{"rendered":"Wieder am Arbeiten, Australien-Party"},"content":{"rendered":"<p>Ich arbeite jetzt seit 1. April beim Wasserwerk Zug als Internet Supporter. Es gibt dort viel zu lernen. Technische Einstellungen, Telefon-Hotline, Emails, Web- und Mailserver, alles sehr interssant.<\/p>\n<p>Am letzten Samstag, 12.4.03 war ich im Albisg\u00fcetli an der Australia-Feeling-Party. Wir hatten ein richtig kleines Klassentreffen. Die Party war nicht schlecht. Nach Hause gings mit dem Nachtnetz vom ZVV und das ohne Probleme, aber mit einem gewissen Zeitaufwand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich arbeite jetzt seit 1. April beim Wasserwerk Zug als Internet Supporter. Es gibt dort viel zu lernen. Technische Einstellungen,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,25],"tags":[],"class_list":["post-950","post","type-post","status-publish","format-standard","hentry","category-australien","category-schweiz"],"_links":{"self":[{"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/posts\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/comments?post=950"}],"version-history":[{"count":1,"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/posts\/950\/revisions"}],"predecessor-version":[{"id":1393,"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/posts\/950\/revisions\/1393"}],"wp:attachment":[{"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/media?parent=950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/categories?post=950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stierli.net\/dominik\/wp-json\/wp\/v2\/tags?post=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}